{"id":11737,"date":"2026-06-28T17:47:00","date_gmt":"2026-06-28T15:47:00","guid":{"rendered":"https:\/\/japankoi-wild.de\/?post_type=product&#038;p=11737"},"modified":"2026-07-12T06:42:39","modified_gmt":"2026-07-12T04:42:39","slug":"beni-kumonryu","status":"publish","type":"product","link":"https:\/\/japankoi-wild.de\/mt\/product\/beni-kumonryu\/","title":{"rendered":"Beni Kumonryu"},"content":{"rendered":"<p>Der Beni Kumonryu begeistert durch den faszinierenden Kontrast aus schwarzer Grundzeichnung und roten Farbpartien. Seine Zeichnung kann sich im Laufe der Zeit ver\u00e4ndern und macht jeden Koi zu einem Unikat. Besonders in klaren Teichen kommt die dynamische Musterung eindrucksvoll zur Geltung.<\/p>\n<p><strong>Genau dieser Koi:<\/strong> Du kaufst den Nishikigoi auf dem Bild: Beni Kumonryu. Keine Beispielabbildung, kein Platzhalter.<\/p>\n<p><strong>F\u00fcr deine Entscheidung:<\/strong> Eckdaten: Variet\u00e4t: Beni Kumonryu, Gr\u00f6\u00dfe: ca. 25 cm, Alter: Tosai (1-j\u00e4hrig), Geschlecht: weiblich, Z\u00fcchter: Kawakami. Aktuell 1x verf\u00fcgbar.<\/p>\n<p><strong>\u00dcbergabe:<\/strong> Nach der Reservierung stimmen wir Abholung oder Koi-Versand pers\u00f6nlich mit dir ab. Bei Fragen zu Teich, Besatz oder Eingew\u00f6hnung beraten wir vor der \u00dcbergabe.<\/p>","protected":false},"excerpt":{"rendered":"<p>Beni Kumonryu \u00b7 ca. 25 cm \u00b7 Tosai (1-j\u00e4hrig) \u00b7 Kawakami<\/p>","protected":false},"featured_media":11640,"template":"","meta":[],"product_brand":[],"product_cat":[16,15],"product_tag":[],"class_list":["post-11737","product","type-product","status-publish","has-post-thumbnail","product_cat-koi-kaufen","product_cat-uncategorized","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/product\/11737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/media?parent=11737"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/product_brand?post=11737"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/product_cat?post=11737"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/japankoi-wild.de\/mt\/wp-json\/wp\/v2\/product_tag?post=11737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}