{"id":7803,"date":"2026-06-21T20:16:00","date_gmt":"2026-06-21T18:16:00","guid":{"rendered":"https:\/\/japankoi-wild.de\/?post_type=product&#038;p=7803"},"modified":"2026-07-12T06:42:39","modified_gmt":"2026-07-12T04:42:39","slug":"hi-utsuri-jumbo-tosai-vhq","status":"publish","type":"product","link":"https:\/\/japankoi-wild.de\/lv\/product\/hi-utsuri-jumbo-tosai-vhq\/","title":{"rendered":"Hi Utsuri Jumbo Tosai VHQ"},"content":{"rendered":"<p>Der Hi Utsuri besticht durch den intensiven Kontrast aus tiefschwarzer Grundfarbe und kr\u00e4ftig roten Zeichnungen. Das ausgewogene Zusammenspiel beider Farben verleiht dieser Variet\u00e4t eine besonders ausdrucksstarke Erscheinung. Hochwertige Hi Utsuri zeichnen sich durch ein sattes Schwarz und ein gleichm\u00e4\u00dfiges, leuchtendes Rot aus.<\/p>\n<p><strong>Genau dieser Koi:<\/strong> Du kaufst den Nishikigoi auf dem Bild: Hi Utsuri Jumbo Tosai VHQ. Keine Beispielabbildung, kein Platzhalter.<\/p>\n<p><strong>F\u00fcr deine Entscheidung:<\/strong> Eckdaten: Variet\u00e4t: Hi Utsuri, Gr\u00f6\u00dfe: 28-30 cm, Alter: Tosai (1-j\u00e4hrig), Geschlecht: weiblich, Z\u00fcchter: Shinoda. Aktuell 1x verf\u00fcgbar.<\/p>\n<p><strong>\u00dcbergabe:<\/strong> Nach der Reservierung stimmen wir Abholung oder Koi-Versand pers\u00f6nlich mit dir ab. Bei Fragen zu Teich, Besatz oder Eingew\u00f6hnung beraten wir vor der \u00dcbergabe.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hi Utsuri \u00b7 28-30cm \u00b7 Tosai (1-j\u00e4hrig) \u00b7 Shinoda<\/p>","protected":false},"featured_media":7793,"template":"","meta":[],"product_brand":[],"product_cat":[16,15],"product_tag":[],"class_list":["post-7803","product","type-product","status-publish","has-post-thumbnail","product_cat-koi-kaufen","product_cat-uncategorized","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/product\/7803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/media?parent=7803"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/product_brand?post=7803"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/product_cat?post=7803"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/japankoi-wild.de\/lv\/wp-json\/wp\/v2\/product_tag?post=7803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}